{"id":15520,"date":"2026-05-11T11:20:25","date_gmt":"2026-05-11T09:20:25","guid":{"rendered":"https:\/\/forum.schreiner-group.com\/?p=15520"},"modified":"2026-05-12T09:15:53","modified_gmt":"2026-05-12T07:15:53","slug":"gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group","status":"publish","type":"post","link":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/","title":{"rendered":"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; content_placement=&#8220;top&#8220; css=&#8220;.vc_custom_1778490660823{margin-top: 150px !important;}&#8220; parallax_background_image=&#8220;15514&#8243;][vc_column][vc_empty_space height=&#8220;615px&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1606213327836{background-color: #ffffff !important;}&#8220; el_class=&#8220;article_bighead&#8220;][vc_column][vc_custom_heading text=&#8220;SCHREINER GROUP&#8220; font_container=&#8220;tag:h2|text_align:center&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;topcategory&#8220;][vc_custom_heading text=&#8220;Gewerbeverband Oberschlei\u00dfheim erlebt zukunftsorientierte Energiekonzepte bei der Schreiner Group&#8220; font_container=&#8220;tag:h1|text_align:center&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.<\/strong>[\/vc_column_text][vc_empty_space height=&#8220;25px&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_column_text]Seit vielen Jahren ist Nachhaltigkeit ein fester Bestandteil der Unternehmensstrategie der Schreiner Group. Ein Meilenstein dabei war die Inbetriebnahme des W\u00e4rmepumpenhauses im Jahr 2023. Vier gro\u00dfe W\u00e4rmepumpen zur Energiegewinnung aus Grundwasser sowie drei weitere dezentrale W\u00e4rmepumpen auf dem Betriebsgel\u00e4nde tragen dazu bei, den Einsatz fossiler Energietr\u00e4ger deutlich zu reduzieren. Insgesamt investierte das Unternehmen rund sechs Millionen Euro in das Projekt.[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]\u201eNachhaltigkeit bedeutet f\u00fcr uns, langfristig Verantwortung zu \u00fcbernehmen und gleichzeitig zukunftsf\u00e4hige L\u00f6sungen f\u00fcr unseren Standort zu schaffen\u201c, betonte Gesch\u00e4ftsf\u00fchrer Roland Schreiner. \u201eMit unserem W\u00e4rmepumpenkonzept haben wir einen wichtigen Schritt unternommen, um unsere Energieversorgung breiter aufzustellen und den CO\u2082-Aussto\u00df im Bereich der W\u00e4rmeversorgung deutlich zu reduzieren.\u201c[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]Beim Rundgang erhielten die Teilnehmer Einblicke in zahlreiche \u00f6kologische Ma\u00dfnahmen, die das Betriebsgel\u00e4nde pr\u00e4gen: Photovoltaikanlagen auf den Parkhausd\u00e4chern, begr\u00fcnte D\u00e4cher sowie Gr\u00fcnfl\u00e4chen mit B\u00e4umen, Str\u00e4uchern und Blumen geh\u00f6ren ebenso dazu wie Nistk\u00e4sten und eigene Bienenst\u00f6cke. Vorgestellt wurde au\u00dferdem Geb\u00e4ude VI, das 2016 eingeweiht wurde und durch sein Energiekonzept besonders ressourcenschonend betrieben wird.[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]\u201eViele Ma\u00dfnahmen greifen bei uns ineinander \u2013 von moderner Geb\u00e4udetechnik bis hin zur Gestaltung der Au\u00dfenfl\u00e4chen\u201c, erkl\u00e4rte Wolfgang Bonnet. \u201eUns ist wichtig, Nachhaltigkeit ganzheitlich zu betrachten und dabei \u00f6kologische Aspekte ebenso mitzudenken wie eine attraktive Arbeitsumgebung.\u201c[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]Die Vorsitzende des Gewerbeverbands Oberschlei\u00dfheim, G\u00f6nke Klar, zeigte sich beeindruckt von den Einblicken vor Ort: \u201e\u00dcber die vielf\u00e4ltigen Nachhaltigkeitsprojekte der Schreiner Group haben wir im Gewerbeverband bereits viel geh\u00f6rt \u2013 umso spannender war es, diese Ma\u00dfnahmen nun direkt vor Ort zu erleben. Der Besuch hat eindrucksvoll gezeigt, mit wie viel Engagement und technischem Know-how das Unternehmen seine Projekte umsetzt.\u201c[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_empty_space height=&#8220;15px&#8220;][vc_single_image image=&#8220;15512&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][vc_empty_space height=&#8220;15px&#8220;][vc_single_image image=&#8220;15508&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][vc_empty_space height=&#8220;15px&#8220;][vc_single_image image=&#8220;15506&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_empty_space height=&#8220;25px&#8220;][vc_single_image image=&#8220;15515&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_empty_space height=&#8220;25px&#8220;][vc_single_image image=&#8220;15509&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.<\/p>\n","protected":false},"author":2,"featured_media":15512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[54],"tags":[227],"class_list":["post-15520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schreiner-group","tag-standorte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group - Schreiner Group Forum<\/title>\n<meta name=\"description\" content=\"Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group - Schreiner Group Forum\" \/>\n<meta property=\"og:description\" content=\"Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Schreiner Group Forum\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T09:20:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T07:15:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"markus.liedl@schreiner-group.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"markus.liedl@schreiner-group.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/\",\"url\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/\",\"name\":\"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group - Schreiner Group Forum\",\"isPartOf\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg\",\"datePublished\":\"2026-05-11T09:20:25+00:00\",\"dateModified\":\"2026-05-12T07:15:53+00:00\",\"author\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc\"},\"description\":\"Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.\",\"breadcrumb\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#primaryimage\",\"url\":\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg\",\"contentUrl\":\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim am Hauptsitz der Schreiner Group.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/forum.schreiner-group.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#website\",\"url\":\"https:\/\/forum.schreiner-group.com\/de\/\",\"name\":\"Schreiner Group Forum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/forum.schreiner-group.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc\",\"name\":\"markus.liedl@schreiner-group.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g\",\"caption\":\"markus.liedl@schreiner-group.com\"},\"url\":\"https:\/\/forum.schreiner-group.com\/de\/author\/markus-liedlschreiner-group-de\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group - Schreiner Group Forum","description":"Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/","og_locale":"de_DE","og_type":"article","og_title":"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group - Schreiner Group Forum","og_description":"Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.","og_url":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/","og_site_name":"Schreiner Group Forum","article_published_time":"2026-05-11T09:20:25+00:00","article_modified_time":"2026-05-12T07:15:53+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg","type":"image\/jpeg"}],"author":"markus.liedl@schreiner-group.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"markus.liedl@schreiner-group.com","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/","url":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/","name":"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group - Schreiner Group Forum","isPartOf":{"@id":"https:\/\/forum.schreiner-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#primaryimage"},"image":{"@id":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#primaryimage"},"thumbnailUrl":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg","datePublished":"2026-05-11T09:20:25+00:00","dateModified":"2026-05-12T07:15:53+00:00","author":{"@id":"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc"},"description":"Wie nachhaltiges Wirtschaften und moderne Energietechnologien in der Praxis zusammenwirken k\u00f6nnen, davon \u00fcberzeugten sich rund 20 Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim bei einem Besuch am Hauptsitz der Schreiner Group. Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die G\u00e4ste pers\u00f6nlich und gab einen kurzen Einblick in die nachhaltige Ausrichtung des Hightech-Unternehmens. Im Anschluss f\u00fchrte Wolfgang Bonnet, Leiter Facility Management, die Besucher \u00fcber das Betriebsgel\u00e4nde.","breadcrumb":{"@id":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#primaryimage","url":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg","contentUrl":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/Gewerbeverband_Oberschleissheim_Besuch_Gruppenbild.jpg","width":1920,"height":1280,"caption":"Gesch\u00e4ftsf\u00fchrer Roland Schreiner begr\u00fc\u00dfte die Teilnehmer des Gewerbeverbands Oberschlei\u00dfheim am Hauptsitz der Schreiner Group."},{"@type":"BreadcrumbList","@id":"https:\/\/forum.schreiner-group.com\/de\/gewerbeverband-oberschleissheim-erlebt-zukunfts-orientierte-energiekonzepte-bei-der-schreiner-group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/forum.schreiner-group.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gewerbeverband Oberschlei\u00dfheim bei der Schreiner Group"}]},{"@type":"WebSite","@id":"https:\/\/forum.schreiner-group.com\/de\/#website","url":"https:\/\/forum.schreiner-group.com\/de\/","name":"Schreiner Group Forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forum.schreiner-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc","name":"markus.liedl@schreiner-group.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g","caption":"markus.liedl@schreiner-group.com"},"url":"https:\/\/forum.schreiner-group.com\/de\/author\/markus-liedlschreiner-group-de\/"}]}},"_links":{"self":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts\/15520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/comments?post=15520"}],"version-history":[{"count":7,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts\/15520\/revisions"}],"predecessor-version":[{"id":15531,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts\/15520\/revisions\/15531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/media\/15512"}],"wp:attachment":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/media?parent=15520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/categories?post=15520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/tags?post=15520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}