{"id":15322,"date":"2026-05-26T14:25:30","date_gmt":"2026-05-26T12:25:30","guid":{"rendered":"https:\/\/forum.schreiner-group.com\/?p=15322"},"modified":"2026-05-26T16:07:15","modified_gmt":"2026-05-26T14:07:15","slug":"10-jahre-erfolg-in-china","status":"publish","type":"post","link":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/","title":{"rendered":"10 Jahre Erfolg in China"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; content_placement=&#8220;top&#8220; css=&#8220;.vc_custom_1777988015188{margin-top: 150px !important;}&#8220; parallax_background_image=&#8220;15310&#8243;][vc_column][vc_empty_space height=&#8220;615px&#8220;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1606213327836{background-color: #ffffff !important;}&#8220; el_class=&#8220;article_bighead&#8220;][vc_column][vc_custom_heading text=&#8220;SCHREINER GROUP&#8220; font_container=&#8220;tag:h2|text_align:center&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;topcategory&#8220;][vc_custom_heading text=&#8220;10 Jahre Erfolg in China&#8220; font_container=&#8220;tag:h1|text_align:center&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.<\/strong>[\/vc_column_text][vc_empty_space height=&#8220;25px&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_column_text]<strong>Mitarbeiter im Mittelpunkt<\/strong><br \/>\nIm Zentrum des Jubil\u00e4ums stand der Austausch mit den Mitarbeitern. In seiner Rede vor der Belegschaft w\u00fcrdigte Roland Schreiner die Entwicklung des Standorts und das Engagement des Teams: \u201eWas hier in den vergangenen zehn Jahren entstanden ist, zeigt eindrucksvoll, wie erfolgreich unsere Internationalisierungsstrategie umgesetzt wird.\u201c[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]<strong>Austausch vor Ort<\/strong><br \/>\nEin zentraler Bestandteil des Besuchs war der Dialog mit der chinesischen Lokalverwaltung sowie mit Kunden. Gemeinsam mit Beh\u00f6rdenvertretern besichtigten Roland Schreiner und Thomas K\u00f6berlein den Industriepark Jinshan. \u201eEin vertrauensvolles Verh\u00e4ltnis zur lokalen Verwaltung ist eine wichtige Grundlage f\u00fcr Stabilit\u00e4t und weiteres Wachstum\u201c, so der Gesch\u00e4ftsbereichsleiter. Auch die Gespr\u00e4che mit Kunden unterstreichen den Wert der lokalen Pr\u00e4senz: N\u00e4he zum Markt, kurze Wege und verl\u00e4ssliche Partnerschaften st\u00e4rken die Position der Schreiner Group im internationalen Umfeld.[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]<strong>Dynamische Entwicklung<\/strong><br \/>\nDer Standort in China wurde 2016 gegr\u00fcndet und hat sich seitdem dynamisch entwickelt. Heute beliefert das Werk sowohl internationale als auch lokale Kunden aus Automotive, General Industry und Pharma. Jamie Long, General Manager der Schreiner Group (Shanghai) Company Ltd., betont: \u201eUnsere Pr\u00e4senz in Shanghai erm\u00f6glicht es uns, sehr nah an unseren Kunden zu sein, ihre Anforderungen genau zu verstehen und schnell in passende L\u00f6sungen umzusetzen.\u201c[\/vc_column_text][vc_empty_space height=&#8220;15px&#8220;][vc_column_text]<strong>Blick nach vorn<\/strong><br \/>\nDas zehnj\u00e4hrige Jubil\u00e4um markiert damit nicht nur einen R\u00fcckblick, sondern auch einen Ausblick. Der Standort Jinshan bleibt ein zentraler Pfeiler der internationalen Strategie der Schreiner Group \u2013 getragen von lokaler Verankerung, globalen Standards und dem kontinuierlichen Dialog mit Mitarbeitern, Partnern und Kunden.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;15320&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][vc_single_image image=&#8220;15318&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][vc_empty_space height=&#8220;15px&#8220;][vc_single_image image=&#8220;15312&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8220;35px&#8220;][vc_single_image image=&#8220;15316&#8243; img_size=&#8220;large&#8220; add_caption=&#8220;yes&#8220; onclick=&#8220;link_image&#8220; css_animation=&#8220;fadeIn&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.<\/p>\n","protected":false},"author":2,"featured_media":15318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[54],"tags":[227],"class_list":["post-15322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schreiner-group","tag-standorte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 Jahre Erfolg in China - Schreiner Group Forum<\/title>\n<meta name=\"description\" content=\"Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Jahre Erfolg in China - Schreiner Group Forum\" \/>\n<meta property=\"og:description\" content=\"Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/\" \/>\n<meta property=\"og:site_name\" content=\"Schreiner Group Forum\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-26T12:25:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T14:07:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"markus.liedl@schreiner-group.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"markus.liedl@schreiner-group.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/\",\"url\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/\",\"name\":\"10 Jahre Erfolg in China - Schreiner Group Forum\",\"isPartOf\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg\",\"datePublished\":\"2026-05-26T12:25:30+00:00\",\"dateModified\":\"2026-05-26T14:07:15+00:00\",\"author\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc\"},\"description\":\"Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.\",\"breadcrumb\":{\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#primaryimage\",\"url\":\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg\",\"contentUrl\":\"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Gesch\u00e4ftsf\u00fchrer Roland Schreiner (Mitte), Thomas K\u00f6berlein (links), Gesch\u00e4ftsbereichsleiter Schreiner ProTech, und Jamie Long (rechts), General Manager der Schreiner Group (Shanghai) Company Ltd., schneiden die Jubil\u00e4umstorte an.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/forum.schreiner-group.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 Jahre Erfolg in China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#website\",\"url\":\"https:\/\/forum.schreiner-group.com\/de\/\",\"name\":\"Schreiner Group Forum\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/forum.schreiner-group.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc\",\"name\":\"markus.liedl@schreiner-group.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g\",\"caption\":\"markus.liedl@schreiner-group.com\"},\"url\":\"https:\/\/forum.schreiner-group.com\/de\/author\/markus-liedlschreiner-group-de\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 Jahre Erfolg in China - Schreiner Group Forum","description":"Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/","og_locale":"de_DE","og_type":"article","og_title":"10 Jahre Erfolg in China - Schreiner Group Forum","og_description":"Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.","og_url":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/","og_site_name":"Schreiner Group Forum","article_published_time":"2026-05-26T12:25:30+00:00","article_modified_time":"2026-05-26T14:07:15+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg","type":"image\/jpeg"}],"author":"markus.liedl@schreiner-group.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"markus.liedl@schreiner-group.com","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/","url":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/","name":"10 Jahre Erfolg in China - Schreiner Group Forum","isPartOf":{"@id":"https:\/\/forum.schreiner-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#primaryimage"},"image":{"@id":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#primaryimage"},"thumbnailUrl":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg","datePublished":"2026-05-26T12:25:30+00:00","dateModified":"2026-05-26T14:07:15+00:00","author":{"@id":"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc"},"description":"Unter dem Motto \u201eInspired by Tradition \u2013 Built for Innovation\u201c er\u00f6ffnete die Schreiner Group im Gro\u00dfraum Shanghai im Fr\u00fchjahr 2016 einen chinesischen Produktionsstandort. Zehn Jahre nach der Gr\u00fcndung hat sich dieser als fester Bestandteil der internationalen Unternehmensstruktur etabliert. Mit ihrem Besuch zum Jubil\u00e4um bekr\u00e4ftigten Gesch\u00e4ftsf\u00fchrer Roland Schreiner und Thomas K\u00f6berlein, Gesch\u00e4ftsbereichsleiter Schreiner ProTech, die strategische Bedeutung des Standorts.","breadcrumb":{"@id":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#primaryimage","url":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg","contentUrl":"https:\/\/forum.schreiner-group.com\/wp-content\/uploads\/2026\/05\/schreiner-group-10-years-China-anniversary-cake.jpg","width":1920,"height":1280,"caption":"Gesch\u00e4ftsf\u00fchrer Roland Schreiner (Mitte), Thomas K\u00f6berlein (links), Gesch\u00e4ftsbereichsleiter Schreiner ProTech, und Jamie Long (rechts), General Manager der Schreiner Group (Shanghai) Company Ltd., schneiden die Jubil\u00e4umstorte an."},{"@type":"BreadcrumbList","@id":"https:\/\/forum.schreiner-group.com\/de\/10-jahre-erfolg-in-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/forum.schreiner-group.com\/de\/"},{"@type":"ListItem","position":2,"name":"10 Jahre Erfolg in China"}]},{"@type":"WebSite","@id":"https:\/\/forum.schreiner-group.com\/de\/#website","url":"https:\/\/forum.schreiner-group.com\/de\/","name":"Schreiner Group Forum","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forum.schreiner-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/bd0e2515cfe9118ea30379405cb6f7dc","name":"markus.liedl@schreiner-group.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forum.schreiner-group.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e83202ed81ba95ae0113c3f2d897918a?s=96&d=mm&r=g","caption":"markus.liedl@schreiner-group.com"},"url":"https:\/\/forum.schreiner-group.com\/de\/author\/markus-liedlschreiner-group-de\/"}]}},"_links":{"self":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts\/15322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/comments?post=15322"}],"version-history":[{"count":4,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts\/15322\/revisions"}],"predecessor-version":[{"id":15330,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/posts\/15322\/revisions\/15330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/media\/15318"}],"wp:attachment":[{"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/media?parent=15322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/categories?post=15322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forum.schreiner-group.com\/de\/wp-json\/wp\/v2\/tags?post=15322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}